{"id":636,"date":"2024-08-09T15:07:01","date_gmt":"2024-08-09T15:07:01","guid":{"rendered":"https:\/\/www.lafattoriadelleginestre.com\/web\/?p=636"},"modified":"2024-08-09T13:57:18","modified_gmt":"2024-08-09T13:57:18","slug":"bambini-e-tecnologia-e-una-vicinanza-sempre-positiva","status":"publish","type":"post","link":"https:\/\/www.lafattoriadelleginestre.com\/web\/2024\/08\/09\/bambini-e-tecnologia-e-una-vicinanza-sempre-positiva\/","title":{"rendered":"Bambini e tecnologia : \u00e8 una vicinanza sempre positiva ?"},"content":{"rendered":"<div class=\"postie-post\">\n<div>\n<div><font face=Calibri><\/font>&nbsp;<\/div>\n<div style=\"FONT: 10pt Tahoma\"><font face=Calibri><\/font>&nbsp;<\/div>\n<p><span   style=\"BACKGROUND: #ffffff; PADDING-BOTTOM: 0px; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 0px; DISPLAY: block; PADDING-RIGHT: 0px\">  <\/p>\n<table id=wysija_wrapper cellspacing=0 cellpadding=0 width=\"100%\" border=0>\n<tbody>\n<tr>\n<td valign=top align=center>\n<table cellspacing=0 cellpadding=0 width=600 align=center border=0>\n<tbody>\n<tr>\n<td style=\"MIN-WIDTH: 600px\" valign=top width=600 align=center>\n<p class=wysija_viewbrowser_container               style=\"FONT-SIZE: 11px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; COLOR: #000000 !important; PADDING-BOTTOM: 8px; TEXT-ALIGN: center; PADDING-TOP: 8px; PADDING-LEFT: 8px; BORDER-LEFT: 0px; PADDING-RIGHT: 8px; BACKGROUND-COLOR: #ffffff\"><font               size=3 face=Calibri><\/font>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"MIN-WIDTH: 600px\" valign=top width=600 align=center>\n<table class=wysija_header               style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; CLEAR: both; BORDER-LEFT: 0px; mso-table-lspace: 0pt; mso-table-rspace: 0pt\"               cellspacing=0 cellpadding=0 width=\"100%\" align=center border=0>\n<tbody>\n<tr>\n<td class=wysija_header_container                   style=\"FONT-SIZE: 1px; BORDER-TOP: 0px; BORDER-RIGHT: 0px; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; BORDER-LEFT: 0px; LINE-HEIGHT: 1%; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly\"                   height=1 align=left><img decoding=\"async\" class=image_fix                     style=\"TEXT-DECORATION: none; BORDER-TOP: 0px; HEIGHT: 83px; BORDER-RIGHT: 0px; WIDTH: 147px; BORDER-BOTTOM: 0px; OUTLINE-WIDTH: 0px; OUTLINE-STYLE: none; BORDER-LEFT: 0px; DISPLAY: block; OUTLINE-COLOR: invert; -MS-INTERPOLATION-MODE: bicubic\"                     border=0 alt=\"\"                     src=\"http:\/\/www.lafattoriadelleginestre.com\/wp-content\/uploads\/2015\/12\/logo.jpg\"                     width=147 height=83> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"MIN-WIDTH: 600px\" valign=top width=600 align=left>\n<table class=wysija_block               style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; CLEAR: both; BORDER-LEFT: 0px; mso-table-lspace: 0pt; mso-table-rspace: 0pt\"               cellspacing=0 cellpadding=0 width=\"100%\" align=left border=0>\n<tbody>\n<tr>\n<td class=\"wysija_content_container center\"                   style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; BORDER-BOTTOM: 0px; PADDING-BOTTOM: 10px; PADDING-TOP: 10px; PADDING-LEFT: 17px; BORDER-LEFT: 0px; PADDING-RIGHT: 17px; BACKGROUND-COLOR: #ffffff\"                   align=left>\n<div class=wysija_text_container>\n<h1                     style=\"FONT-SIZE: 34px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; FONT-WEIGHT: normal; COLOR: #000000 !important; PADDING-BOTTOM: 0px; FONT-STYLE: normal; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 0px; BORDER-LEFT: 0px; LETTER-SPACING: normal; LINE-HEIGHT: 125%; PADDING-RIGHT: 0px; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><span                     style=\"COLOR: rgb(53,99,19)\"><em><strong>La Fattoria delle                     Ginestre<\/strong><\/em><\/span><\/h1>\n<h2                     style=\"FONT-SIZE: 16px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; FONT-WEIGHT: normal; COLOR: #424242 !important; PADDING-BOTTOM: 0px; FONT-STYLE: normal; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 0px; BORDER-LEFT: 0px; LETTER-SPACING: normal; LINE-HEIGHT: 125%; PADDING-RIGHT: 0px; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><span                     style=\"COLOR: rgb(128,128,128)\"><strong>Fattoria didattica &#8211;                     Agriturismo culturale &nbsp;&#8211; Formazione<br                     style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; PADDING-BOTTOM: 0px; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 0px; BORDER-LEFT: 0px; LINE-HEIGHT: 150%; PADDING-RIGHT: 0px; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><\/strong><\/span><span                     style=\"COLOR: rgb(128,128,128)\"><strong>Progetti creativi,                     educativi,               ricreativi<\/strong><\/span><\/h2>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=wysija_block               style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; CLEAR: both; BORDER-LEFT: 0px; mso-table-lspace: 0pt; mso-table-rspace: 0pt\"               cellspacing=0 cellpadding=0 width=\"100%\" align=left border=0>\n<tbody>\n<tr                 style=\"FONT-SIZE: 1px; mso-line-height-alt: 0; mso-margin-top-alt: 1px\">\n<td class=wysija_divider_container                   style=\"BORDER-TOP: 0px; HEIGHT: 25px; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; PADDING-BOTTOM: 15px; PADDING-TOP: 15px; PADDING-LEFT: 17px; BORDER-LEFT: 0px; PADDING-RIGHT: 17px; BACKGROUND-COLOR: #ffffff\"                   valign=middle width=\"100%\" align=left>\n<div align=center><font size=3 face=Calibri><\/font><img decoding=\"async\"                     class=image_fix                     style=\"TEXT-DECORATION: none; BORDER-TOP: 0px; HEIGHT: 25px; BORDER-RIGHT: 0px; WIDTH: 564px; BORDER-BOTTOM: 0px; OUTLINE-WIDTH: 0px; OUTLINE-STYLE: none; BORDER-LEFT: 0px; DISPLAY: block; OUTLINE-COLOR: invert; -MS-INTERPOLATION-MODE: bicubic\"                     border=0 alt=---                     src=\"http:\/\/www.lafattoriadelleginestre.com\/wp-content\/uploads\/wysija\/dividers\/business.png\"                     width=564 height=25> <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=wysija_block               style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; CLEAR: both; BORDER-LEFT: 0px; mso-table-lspace: 0pt; mso-table-rspace: 0pt\"               cellspacing=0 cellpadding=0 width=\"100%\" align=left border=0>\n<tbody>\n<tr>\n<td class=\"wysija_content_container center\"                   style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; BORDER-BOTTOM: 0px; PADDING-BOTTOM: 10px; PADDING-TOP: 10px; PADDING-LEFT: 17px; BORDER-LEFT: 0px; PADDING-RIGHT: 17px; BACKGROUND-COLOR: #ffffff\"                   align=left>\n<div class=wysija_text_container><font face=Century><font                     face=Century><font face=Century><span                     style=\"FONT-FAMILY: Calibri\"><font                     style=\"BACKGROUND-COLOR: #ffffff\"><font size=2><font                     face=Century><font color=#800000 size=3><font                     face=Century><font color=#000000><\/font>                    <\/p>\n<div>\n<div><font color=#800000 size=4>Bambini e                     tecnologia<\/font><\/div>\n<div><font color=#800000 size=4>\u00e8 sempre una vicinanza                     &nbsp;positiva ? <\/font><\/div>\n<\/div>\n<div><font color=#000000>                    <\/p>\n<div>&nbsp;&nbsp;                     <\/p>\n<div>&nbsp;<\/div>\n<div>Non si capisce perch\u00e9&#8230; Anche senza essere pedagogisti o                     medici direi che l&#8217; informazione e ( speriamo ) la riflessione                     sugli effetti negativi di una precoce esposizione dei pi\u00f9                     piccoli a giochi ed intrattenimenti elettronici, a telefoni e                     tablet sia ben nota. <\/div>\n<div>&nbsp;<\/div>\n<div>E allora perch\u00e9 si continua a farlo, a propinarli ai                     bambini,&nbsp;con sorprendente disinvoltura ? <\/div>\n<div>Tablet da viaggio e da passeggio gi\u00e0 per neonati ( visti                     con i miei occhi ), bambini che vengono &#8221; silenziati&#8221; dando                     loro un telefono in mano, adulti&nbsp;allo scacco delle                     pressioni tecnologiche dei figli. Io sono allibita da tale &#8221;                     disinvoltura&#8221;.<\/div>\n<div>( e so bene che scrivendo questo posso anche risultare                     poco &#8221; simpatica&#8221; ) &nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>E&#8217; evidente che non si vuole fare nessuna crociata contro                     la tecnologia e contro le innovazioni. Per\u00f2 questo &#8211;                     soprattutto quando si ha a che vedere con soggetti &#8221; delicati&#8221;                     come i bambini e gli adolescenti- deve essere un argomento da                     approfondire e assolutamente da regolare<\/div>\n<div><font face=Calibri><\/font>&nbsp;<\/div>\n<div><font face=Calibri><font face=Century>Una circolare del                     luglio 2024 , del Ministro dell&#8217;istruzione Valditara ,                     percepisce questa problematica decretando lo &#8221; stop del                     cellulare in classe &#8221; ed il ritorno al diario cartaceo per                     riabituare i bambini a scrivere ( avete letto bene :                     riabituare a scrivere ! ) . A scuola l&#8217;uso dei cellulari sar\u00e0                     proibito fino alle medie<\/font> <font                     face=Century>.<\/font>&nbsp;<\/font><\/div>\n<div>&nbsp;<\/div>\n<div>Come mai non risulta per\u00f2 evidente ( e, a mio avviso,                     &nbsp;non viene sottolineato abbastanza da chi fa didattica                     )&nbsp; quella che \u00e8 oggi la forte diminuzione dei tempi di                     attenzione dei bambini, la difficolt\u00e0 di concentrazione, la                     passivit\u00e0 e spesso la demotivazione, il malumore e talvolta                     gli atteggiamenti aggressivi o scontrosi, la fragilit\u00e0 sul                     piano immaginativo, la difficolt\u00e0 a relazionarsi con le                     emozioni &nbsp;&nbsp;&#8230;?<\/div>\n<div>&nbsp;<\/div>\n<div>Oggi si&nbsp;stanno &#8220;attaccando&#8221; un sacco di etichette                     sui bambini ( BES, DSA, Disturbo oppositivo provocatorio,                     ipercinetismo &#8230;eccetera) e tutto ci\u00f2 &nbsp;gi\u00e0 nella scuola                     dell&#8217; infanzia, senza avviare nessuna riflessione su come                     vengono educati i bambini oggi. Credo che almeno una minima                     correlazione tra la diminuzione dell&#8217; azione, della                     sperimentazione, del fare concreto e tutto questo sia                     intuibile. <\/div>\n<div>&nbsp;<\/div>\n<div>Il gioco \u00e8 il principale strumento di conoscenza almeno                     nei bambini da 0 a 6 anni ( e anche pi\u00f9 ). Ma quali sono i                     giochi preferiti ? Che occasioni hanno di vero gioco ? Come                     giocano i bambini oggi ? Che cultura&nbsp; esprime il                     nostro&nbsp;Paese sul gioco e sui giocattoli ? <\/div>\n<div>Credetemi che non sono argomenti banali soprattutto se                     pensiamo che il mercato del giocattolo ( reale )ormai orienta                     le sue proposte solo sui primissimi anni di vita del bambino                     dato che &nbsp;il mercato dei giochi elettronici ha raggiunto                     quasi l&#8217;80 % del fatturato .<\/div>\n<div>&nbsp;<\/div>\n<div>Vi parlo di questi argomenti perch\u00e9 ne riconosco                     l&#8217;assoluta importanza. <\/div>\n<div>&nbsp;<\/div>\n<div><em>Anche per questo possiamo considerare Fattoria delle                     ginestre&nbsp;un vero e proprio avamposto di &#8221; buon gioco &#8221; e                     di educazione in natura attraverso il &#8221; fare e lo                     sperimentare&#8221; .<\/em> Lo facciamo ininterrottamente da 25 anni,                     perch\u00e9 siamo convinti della validit\u00e0 e della necessit\u00e0 di                     questo approccio . Oggi pi\u00f9 che mai. <\/div>\n<div>&nbsp;<\/div>\n<div>Siamo un centro culturale e fattoria didattica aperta                     tutto l&#8217;anno con un&#8217;offerta educativa &#8211; ricreativa molto ampia                     durante il periodo estivo e credetemi che&nbsp;molto tempo                     viene da noi &nbsp;investito per insegnare ai bambini a                     giocare ( conoscere e rispettare le regole , essere creativi ,                     sviluppare abilit\u00e0, relazionarsi con gli altri, coinvolgersi                     nell&#8217;azione ludica ..) e poi per strutturare nuovi giochi e                     nuove esperienze volte allo sviluppo delle competenze e degli                     interessi di ogni specifico gruppo .<\/div>\n<div>I risultati ci sono: eccome ! <\/div>\n<div>Ed \u00e8 proprio per questo che cerchiamo di divulgare tali                     necessit\u00e0, mostrandone l&#8217;efficacia . <\/div>\n<div>&nbsp;&nbsp;&nbsp;<\/div>\n<div>Carissimi, in conclusione, siamo sicuri che la nostra                     societ\u00e0 riservi ai bambini ci\u00f2 di cui veramente hanno bisogno?                     <\/div>\n<div>Se cos\u00ec non fosse andrebbe cambiata. Ed \u00e8 compito di                     ciascuno di noi farlo . Grazie. <\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Silvana Sperati&nbsp;<\/div>\n<div>Fattoria delle ginestre &nbsp;<\/div>\n<p><font                     color=#000000>&nbsp;&nbsp;<\/font><\/div>\n<p><\/font><\/div>\n<div><font                     color=#000000>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/font><\/div>\n<p style=\"MARGIN-BOTTOM: 0cm\"><font color=#000000 size=3                     face=Calibri><\/font><font color=#000000 size=3                     face=Calibri><\/font><br \/><font                     color=#000000><\/font><\/font><\/P><\/font><\/font><\/font><\/font><\/span><\/font><\/font><\/font>                    <\/p>\n<p                     style=\"WORD-WRAP: break-word; FONT-SIZE: 18px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; VERTICAL-ALIGN: top; BORDER-BOTTOM: 0px; COLOR: #000000 !important; PADDING-BOTTOM: 0px; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 1em 0px; BORDER-LEFT: 0px; LETTER-SPACING: normal; LINE-HEIGHT: 150%; PADDING-RIGHT: 0px; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><font                     style=\"BACKGROUND-COLOR: #ffffff\" size=2><\/font><font                     face=Century><\/font>&nbsp;<\/p>\n<p class=align-center                     style=\"WORD-WRAP: break-word; FONT-SIZE: 18px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; VERTICAL-ALIGN: top; BORDER-BOTTOM: 0px; COLOR: #000000 !important; PADDING-BOTTOM: 0px; TEXT-ALIGN: center; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 1em 0px; BORDER-LEFT: 0px; LETTER-SPACING: normal; LINE-HEIGHT: 150%; PADDING-RIGHT: 0px; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><span                     style=\"FONT-FAMILY: Calibri\"><\/span><font size=3><\/font><font                     face=Century>&nbsp;<font size=3 face=Century><font                     face=Century><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"COLOR: rgb(255,0,255)\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-FAMILY: Calibri\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-FAMILY: Calibri\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-FAMILY: Calibri\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-FAMILY: Calibri\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"FONT-SIZE: large; FONT-FAMILY: Times New Roman\"><span                     style=\"COLOR: rgb(0,0,0)\"><span                     style=\"FONT-FAMILY: Calibri\"><strong><font size=3                     face=Century><font                     face=Century>&nbsp;<\/font><\/font><\/strong><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/font><\/font><\/font><\/p>\n<p                     style=\"WORD-WRAP: break-word; FONT-SIZE: 18px; BORDER-TOP: 0px; FONT-FAMILY: Arial, 'Helvetica Neue', Helvetica, sans-serif; BORDER-RIGHT: 0px; VERTICAL-ALIGN: top; BORDER-BOTTOM: 0px; COLOR: #000000 !important; PADDING-BOTTOM: 0px; PADDING-TOP: 0px; PADDING-LEFT: 0px; MARGIN: 1em 0px; BORDER-LEFT: 0px; LETTER-SPACING: normal; LINE-HEIGHT: 150%; PADDING-RIGHT: 0px; BACKGROUND-COLOR: #ffffff; mso-line-height-rule: exactly; -mso-line-height-rule: exactly\"><font                     face=Century><font face=Century><font face=Century><font                     face=Century><\/font><\/font><\/font><\/font>&nbsp;<\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=wysija_block               style=\"BORDER-TOP: 0px; BORDER-RIGHT: 0px; BORDER-COLLAPSE: collapse; MIN-WIDTH: 100%; BORDER-BOTTOM: 0px; CLEAR: both; BORDER-LEFT: 0px; mso-table-lspace: 0pt; mso-table-rspace: 0pt\"               cellspacing=0 cellpadding=0 width=\"100%\" align=left border=0>\n<tbody>\n<tr                 style=\"FONT-SIZE: 1px; mso-line-height-alt: 0; mso-margin-top-alt: 1px\">\n<td class=wysija_divider_container                   style=\"BORDER-TOP: 0px; HEIGHT: 25px; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; PADDING-BOTTOM: 15px; PADDING-TOP: 15px; PADDING-LEFT: 17px; BORDER-LEFT: 0px; PADDING-RIGHT: 17px; BACKGROUND-COLOR: #ffffff\"                   valign=middle width=\"100%\" align=left>\n<div align=center><font face=Century><img decoding=\"async\" class=image_fix                     style=\"TEXT-DECORATION: none; BORDER-TOP: 0px; HEIGHT: 25px; BORDER-RIGHT: 0px; WIDTH: 564px; BORDER-BOTTOM: 0px; OUTLINE-WIDTH: 0px; OUTLINE-STYLE: none; BORDER-LEFT: 0px; DISPLAY: block; OUTLINE-COLOR: invert; -MS-INTERPOLATION-MODE: bicubic\"                     border=0 alt=---                     src=\"http:\/\/www.lafattoriadelleginestre.com\/wp-content\/uploads\/wysija\/dividers\/business.png\"                     width=564 height=25> <\/font><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"MIN-WIDTH: 600px\" valign=top width=600 align=center><font               face=Century><\/font><\/td>\n<\/tr>\n<tr>\n<td style=\"MIN-WIDTH: 600px\" valign=top width=600 align=center>\n<p class=wysija_unsubscribe_container               style=\"FONT-SIZE: 12px; BORDER-TOP: 0px; FONT-FAMILY: Verdana, Geneva, sans-serif; BORDER-RIGHT: 0px; BORDER-BOTTOM: 0px; COLOR: #000000 !important; PADDING-BOTTOM: 8px; TEXT-ALIGN: center; PADDING-TOP: 8px; PADDING-LEFT: 8px; BORDER-LEFT: 0px; PADDING-RIGHT: 8px; BACKGROUND-COLOR: #ffffff\"><font               face=Century><\/font><br \/>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/span><img decoding=\"async\"   border=0 alt=\"\"   src=\"http:\/\/www.lafattoriadelleginestre.com\/?email_id=351&amp;user_id=960&amp;controller=stats&amp;action=analyse&amp;wysija-page=1&amp;render=1&amp;wysijap=subscriptions-11\"   width=39 height=1> <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; La Fattoria delle Ginestre Fattoria didattica &#8211; Agriturismo culturale &nbsp;&#8211; FormazioneProgetti creativi, educativi, ricreativi Bambini e tecnologia \u00e8 sempre una vicinanza &nbsp;positiva ? &nbsp;&nbsp; &nbsp; Non si capisce perch\u00e9&#8230; Anche senza essere pedagogisti o medici direi che l&#8217; informazione e ( speriamo ) la riflessione sugli effetti negativi di una precoce esposizione dei pi\u00f9 piccoli a giochi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-636","post","type-post","status-publish","format-standard","hentry","category-pensieri"],"_links":{"self":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/posts\/636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/comments?post=636"}],"version-history":[{"count":1,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/posts\/636\/revisions"}],"predecessor-version":[{"id":637,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/posts\/636\/revisions\/637"}],"wp:attachment":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/media?parent=636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/categories?post=636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/tags?post=636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}