{"id":53,"date":"2024-01-04T12:24:33","date_gmt":"2024-01-04T12:24:33","guid":{"rendered":"https:\/\/www.lafattoriadelleginestre.com\/web\/?page_id=53"},"modified":"2024-01-22T08:56:58","modified_gmt":"2024-01-22T08:56:58","slug":"famiglie-insieme","status":"publish","type":"page","link":"https:\/\/www.lafattoriadelleginestre.com\/web\/famiglie-insieme\/","title":{"rendered":"Famiglie insieme"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.lafattoriadelleginestre.com\/web\/cosa-facciamo\/\" data-type=\"page\" data-id=\"164\">Cosa Facciamo<\/a> > Famiglie insieme<\/p>\n\n\n\n<!DOCTYPE html>\n<html>\n  <head>\n    <meta http-equiv=\"content-type\" content=\"text\/html; charset=UTF-8\">\n    <title><\/title>\n  <\/head>\n  <body>\n    <p><font color=\"#000000\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">Dal\n            suo avvio, alla fine degli anni 90, la Fattoria si \u00e8 subito\n            dimostrata \u201cun posto speciale per la famiglia\u201d sia per i numerosi\n            servizi che offre sia per il sostegno dato al difficile \u201cmestiere\u201d\n            di genitore. La Fattoria \u00e8 soprattutto una comunit\u00e0, che grazie a\n            internet si allarga a tanti amici, con i quali \u00e8 possibile\n            ritrovarsi, confrontarsi, condividere.<\/font><\/font><\/font><\/p>\n    <p><font color=\"#000000\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\"><br>\n          <\/font><\/font><\/font>\n    <\/p>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">Cosa\n            propone?<\/font><\/font><\/font><\/p><br>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">Le&nbsp;<i><b>conversazioni<\/b><\/i>&nbsp;tra\ngenitori\n            ed esperti per confrontarsi e affrontare in gruppo le\n            problematiche pi\u00f9 ricorrenti che troppo spesso i genitori si trovano\n            a gestire da soli.<\/font><\/font><\/font><\/p><br>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">Il&nbsp;<i><b>servizio\n                newsletter<\/b><\/i>&nbsp;che \u201ctiene compagnia\u201d riflettendo sui\n            problemi educativi, raccontando il territorio e le sue emozioni,\n            commentando le notizie, informando sui programmi<\/font><\/font><\/font><\/p><br>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">Le&nbsp;<i><b>proposte\n                di formazione<\/b><\/i>&nbsp;dedicate anche ai genitori, perch\u00e9 \u00e8\n            bello, tutti insieme, apprendere semplici tecniche magari per\n            costruire un buon gioco o per diventare migliori narratori di fiabe.<\/font><\/font><\/font><\/p><br>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">I&nbsp;<i><b>momenti\n                di festa e di gioco:&nbsp;<\/b><\/i>occasioni uniche per\n            l\u2019autenticit\u00e0,\n            la cura, la tipologia delle proposte ludiche che coinvolgono\n            genitori\n            e bambini.<\/font><\/font><\/font><\/p><br>\n    <p style=\"font-weight: normal; line-height: 115%; margin-bottom: 0.25cm\" align=\"left\">\n      <font color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\">I&nbsp;<i><b>laboratori\n                per genitori e bambini<\/b><\/i>, occasioni straordinarie dove\n            \u201cfare\n            per capire\u201d. Qui, come suggerisce Bruno Munari, gli adulti possono\n            solo dare indicazioni tecniche, ma non dire ai bimbi cosa si fa.\n            Entrambi al tavolo dell\u2019esperienza per scoprire come \u00e8 fatto il\n            mondo !<\/font><\/font><\/font><\/p><br>\n    <p style=\"line-height: 115%; margin-bottom: 0.25cm\" align=\"left\"><font color=\"#333333\"><font\n\n          face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font style=\"font-size: 12pt\"\n\n            size=\"3\"><span style=\"font-weight: normal\">I&nbsp;<\/span><\/font><\/font><\/font><font\n\n        color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\"><i><b>compleanni<\/b><\/i><\/font><\/font><\/font><font\n\n        color=\"#333333\"><font face=\"Verdana, Helvetica Neue, Helvetica, Arial, sans-serif\"><font\n\n            style=\"font-size: 12pt\" size=\"3\"><span style=\"font-weight: normal\">&nbsp;diventano\nvera\n              festa grazie a proposte, mai uguali, ma sempre progettate a\n              partire dagli interessi del bimbo; riservando una particolare\n              attenzione nel costruire un evento da ricordare, sia con proposte\n              di\n              gioco, di animazione oppure di laboratorio<\/span><\/font><\/font><\/font><\/p><br>\n    <p><\/p>\n  <\/body>\n<\/html>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Fare clic sull&#8217;immagine per ingrandirla<\/em><\/p>\n\n\n\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Cosa Facciamo > Famiglie insieme Dal suo avvio, alla fine degli anni 90, la Fattoria si \u00e8 subito dimostrata \u201cun posto speciale per la famiglia\u201d sia per i numerosi servizi che offre sia per il sostegno dato al difficile \u201cmestiere\u201d di genitore. La Fattoria \u00e8 soprattutto una comunit\u00e0, che grazie a internet si allarga a tanti amici, con i quali [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-53","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":5,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/53\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/53\/revisions\/462"}],"wp:attachment":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/media?parent=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}