{"id":166,"date":"2024-01-10T13:00:33","date_gmt":"2024-01-10T13:00:33","guid":{"rendered":"https:\/\/www.lafattoriadelleginestre.com\/web\/?page_id=166"},"modified":"2024-02-01T10:29:24","modified_gmt":"2024-02-01T10:29:24","slug":"come-contattarci","status":"publish","type":"page","link":"https:\/\/www.lafattoriadelleginestre.com\/web\/come-contattarci\/","title":{"rendered":"Come contattarci"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ci troviamo all&#8217;interno del <a href=\"https:\/\/www.lafattoriadelleginestre.com\/web\/prima-collina\/\" data-type=\"link\" data-id=\"https:\/\/www.lafattoriadelleginestre.com\/web\/prima-collina\/\">Territorio della prima collina<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Frazione Genestrello, 12, 27054, Montebello della Battaglia, Pavia <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/maps.app.goo.gl\/1HWuQNXzsuUPkzjj7\" data-type=\"link\" data-id=\"https:\/\/maps.app.goo.gl\/1HWuQNXzsuUPkzjj7\">Apri la mappa di Google Maps per ottenere indicazioni.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEL. +39 0383 83831<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CEL. +39 347 964 8374 &#8211; Silvana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CEL. +39 331 732 8753 &#8211; Ginevra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indirizzo e-mail: <a href=\"mailto:eureka@lafattoriadelleginestre.com\">eureka@lafattoriadelleginestre.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indirizzo PEC: <a href=\"mailto:fattoriaginestre@pec.it\">fattoriaginestre@pec.it<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compila i campi qui sotto, e invia direttamente un messaggio alla Fattoria!<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-0fff4e4b-0a7c-4149-81a4-b54ceb43342a wpforms-render-modern\" id=\"wpforms-627\"><form id=\"wpforms-form-627\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"627\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/web\/wp-json\/wp\/v2\/pages\/166\" data-token=\"9a41ef67d6a93d00f8c0fb0942b69e73\" data-token-time=\"1788324829\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Abilita JavaScript nel browser per completare questo modulo.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-627-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-627-field_0\">Nome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-627-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" aria-errormessage=\"wpforms-627-field_0-error\" required><\/div><div id=\"wpforms-627-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-627-field_1\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-627-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-627-field_1-error\" required><\/div><div id=\"wpforms-627-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-627-field_3\">Oggetto <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-627-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-627-field_3-error\" required><\/div><div id=\"wpforms-627-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-627-field_2\">Messaggio <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-627-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-627-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"627\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/166\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-627\" class=\"wpforms-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"Invia\" aria-live=\"assertive\" value=\"wpforms-submit\">Invia<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Caricamento\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Ci troviamo all&#8217;interno del Territorio della prima collina Frazione Genestrello, 12, 27054, Montebello della Battaglia, Pavia Apri la mappa di Google Maps per ottenere indicazioni. TEL. +39 0383 83831 CEL. +39 347 964 8374 &#8211; Silvana CEL. +39 331 732 8753 &#8211; Ginevra Indirizzo e-mail: eureka@lafattoriadelleginestre.com Indirizzo PEC: fattoriaginestre@pec.it Compila i campi qui sotto, e invia direttamente un messaggio alla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-166","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/comments?post=166"}],"version-history":[{"count":7,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/166\/revisions"}],"predecessor-version":[{"id":632,"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/pages\/166\/revisions\/632"}],"wp:attachment":[{"href":"https:\/\/www.lafattoriadelleginestre.com\/web\/wp-json\/wp\/v2\/media?parent=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}